{"id":526,"date":"2024-06-09T19:02:15","date_gmt":"2024-06-09T17:02:15","guid":{"rendered":"http:\/\/miralles-abogados.com\/team\/sergio-solanas\/"},"modified":"2025-03-08T11:06:01","modified_gmt":"2025-03-08T10:06:01","slug":"sergio-solanas","status":"publish","type":"member","link":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/","title":{"rendered":"Sergio Solanas"},"content":{"rendered":"\n<p>A partner at Miralles Abogados since 2016, he has been working for the firm since 2001.<\/p>\n\n\n\n<p>He has extensive experience in numerous, highly complex legal cases in all the courts within social and administrative jurisdiction.<\/p>\n\n\n\n<p>He has participated in corporate restructurings, cases concerning employment regulation, corporate restructurings and the modification of working conditions.<\/p>\n","protected":false},"featured_media":665,"template":"","meta":{"_acf_changed":true},"class_list":["post-526","member","type-member","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sergio Solanas - Miralles Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sergio Solanas - Miralles Abogados\" \/>\n<meta property=\"og:description\" content=\"A partner at Miralles Abogados since 2016, he has been working for the firm since 2001. He has extensive experience in numerous, highly complex legal cases in all the courts within social and administrative jurisdiction. He has participated in corporate restructurings, cases concerning employment regulation, corporate restructurings and the modification of working conditions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/\" \/>\n<meta property=\"og:site_name\" content=\"Miralles Abogados\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-08T10:06:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/miralles-abogados.com\/wp-content\/uploads\/2024\/06\/sergio-solanas-normal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"664\" \/>\n\t<meta property=\"og:image:height\" content=\"958\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/team\\\/sergio-solanas\\\/\",\"url\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/team\\\/sergio-solanas\\\/\",\"name\":\"Sergio Solanas - Miralles Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/team\\\/sergio-solanas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/team\\\/sergio-solanas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/miralles-abogados.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/sergio-solanas-normal.jpg\",\"datePublished\":\"2024-06-09T17:02:15+00:00\",\"dateModified\":\"2025-03-08T10:06:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/team\\\/sergio-solanas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/team\\\/sergio-solanas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/team\\\/sergio-solanas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/miralles-abogados.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/sergio-solanas-normal.jpg\",\"contentUrl\":\"https:\\\/\\\/miralles-abogados.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/sergio-solanas-normal.jpg\",\"width\":664,\"height\":958},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/team\\\/sergio-solanas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sergio Solanas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/\",\"name\":\"Miralles Abogados\",\"description\":\"Miralles Abogados\",\"publisher\":{\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/#organization\"},\"alternateName\":\"Miralles Abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/#organization\",\"name\":\"Miralles Abogados\",\"alternateName\":\"Miralles Abogados\",\"url\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miralles-abogados.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-miralles.jpg\",\"contentUrl\":\"https:\\\/\\\/miralles-abogados.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo-miralles.jpg\",\"width\":88,\"height\":88,\"caption\":\"Miralles Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/miralles-abogados.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sergio Solanas - Miralles Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/","og_locale":"en_US","og_type":"article","og_title":"Sergio Solanas - Miralles Abogados","og_description":"A partner at Miralles Abogados since 2016, he has been working for the firm since 2001. He has extensive experience in numerous, highly complex legal cases in all the courts within social and administrative jurisdiction. He has participated in corporate restructurings, cases concerning employment regulation, corporate restructurings and the modification of working conditions.","og_url":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/","og_site_name":"Miralles Abogados","article_modified_time":"2025-03-08T10:06:01+00:00","og_image":[{"width":664,"height":958,"url":"https:\/\/miralles-abogados.com\/wp-content\/uploads\/2024\/06\/sergio-solanas-normal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/","url":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/","name":"Sergio Solanas - Miralles Abogados","isPartOf":{"@id":"https:\/\/miralles-abogados.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/#primaryimage"},"image":{"@id":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/#primaryimage"},"thumbnailUrl":"https:\/\/miralles-abogados.com\/wp-content\/uploads\/2024\/06\/sergio-solanas-normal.jpg","datePublished":"2024-06-09T17:02:15+00:00","dateModified":"2025-03-08T10:06:01+00:00","breadcrumb":{"@id":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/#primaryimage","url":"https:\/\/miralles-abogados.com\/wp-content\/uploads\/2024\/06\/sergio-solanas-normal.jpg","contentUrl":"https:\/\/miralles-abogados.com\/wp-content\/uploads\/2024\/06\/sergio-solanas-normal.jpg","width":664,"height":958},{"@type":"BreadcrumbList","@id":"https:\/\/miralles-abogados.com\/en\/team\/sergio-solanas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/miralles-abogados.com\/en\/"},{"@type":"ListItem","position":2,"name":"Sergio Solanas"}]},{"@type":"WebSite","@id":"https:\/\/miralles-abogados.com\/en\/#website","url":"https:\/\/miralles-abogados.com\/en\/","name":"Miralles Abogados","description":"Miralles Abogados","publisher":{"@id":"https:\/\/miralles-abogados.com\/en\/#organization"},"alternateName":"Miralles Abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miralles-abogados.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/miralles-abogados.com\/en\/#organization","name":"Miralles Abogados","alternateName":"Miralles Abogados","url":"https:\/\/miralles-abogados.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/miralles-abogados.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/miralles-abogados.com\/wp-content\/uploads\/2025\/04\/logo-miralles.jpg","contentUrl":"https:\/\/miralles-abogados.com\/wp-content\/uploads\/2025\/04\/logo-miralles.jpg","width":88,"height":88,"caption":"Miralles Abogados"},"image":{"@id":"https:\/\/miralles-abogados.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/miralles-abogados.com\/en\/wp-json\/wp\/v2\/member\/526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miralles-abogados.com\/en\/wp-json\/wp\/v2\/member"}],"about":[{"href":"https:\/\/miralles-abogados.com\/en\/wp-json\/wp\/v2\/types\/member"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miralles-abogados.com\/en\/wp-json\/wp\/v2\/media\/665"}],"wp:attachment":[{"href":"https:\/\/miralles-abogados.com\/en\/wp-json\/wp\/v2\/media?parent=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}